{"id":194,"count":3,"description":"","link":"https:\/\/sexducacion.com\/ca\/category\/genere\/","name":"G\u00e8nere","slug":"genere","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G\u00e8nere archivos | Sexducacion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sexducacion.com\/ca\/category\/genere\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G\u00e8nere archivos | Sexducacion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sexducacion.com\/ca\/category\/genere\/\" \/>\n<meta property=\"og:site_name\" content=\"Sexducacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/category\\\/genere\\\/\",\"url\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/category\\\/genere\\\/\",\"name\":\"G\u00e8nere archivos | Sexducacion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/category\\\/genere\\\/#breadcrumb\"},\"inLanguage\":\"cat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/category\\\/genere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/inici\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G\u00e8nere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/\",\"name\":\"Sexducacion\",\"description\":\"Espacio online de educaci\u00f3n sexual dirigido a familias, profesionales y toda persona interesada en la educaci\u00f3n sexual.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cat\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/#organization\",\"name\":\"Sexducacion\",\"url\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cat\",\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sexducacion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo-corazo\u0301n-fuerte.png\",\"contentUrl\":\"https:\\\/\\\/sexducacion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo-corazo\u0301n-fuerte.png\",\"width\":1819,\"height\":545,\"caption\":\"Sexducacion\"},\"image\":{\"@id\":\"https:\\\/\\\/sexducacion.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G\u00e8nere archivos | Sexducacion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sexducacion.com\/ca\/category\/genere\/","og_locale":"en_US","og_type":"article","og_title":"G\u00e8nere archivos | Sexducacion","og_url":"https:\/\/sexducacion.com\/ca\/category\/genere\/","og_site_name":"Sexducacion","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sexducacion.com\/ca\/category\/genere\/","url":"https:\/\/sexducacion.com\/ca\/category\/genere\/","name":"G\u00e8nere archivos | Sexducacion","isPartOf":{"@id":"https:\/\/sexducacion.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/sexducacion.com\/ca\/category\/genere\/#breadcrumb"},"inLanguage":"cat"},{"@type":"BreadcrumbList","@id":"https:\/\/sexducacion.com\/ca\/category\/genere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sexducacion.com\/ca\/inici\/"},{"@type":"ListItem","position":2,"name":"G\u00e8nere"}]},{"@type":"WebSite","@id":"https:\/\/sexducacion.com\/ca\/#website","url":"https:\/\/sexducacion.com\/ca\/","name":"Sexducacion","description":"Espacio online de educaci\u00f3n sexual dirigido a familias, profesionales y toda persona interesada en la educaci\u00f3n sexual.","publisher":{"@id":"https:\/\/sexducacion.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sexducacion.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cat"},{"@type":"Organization","@id":"https:\/\/sexducacion.com\/ca\/#organization","name":"Sexducacion","url":"https:\/\/sexducacion.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"cat","@id":"https:\/\/sexducacion.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/sexducacion.com\/wp-content\/uploads\/2022\/06\/Logo-corazo\u0301n-fuerte.png","contentUrl":"https:\/\/sexducacion.com\/wp-content\/uploads\/2022\/06\/Logo-corazo\u0301n-fuerte.png","width":1819,"height":545,"caption":"Sexducacion"},"image":{"@id":"https:\/\/sexducacion.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sexducacion.com\/ca\/wp-json\/wp\/v2\/categories\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sexducacion.com\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sexducacion.com\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sexducacion.com\/ca\/wp-json\/wp\/v2\/posts?categories=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}